﻿{"id":1253,"date":"2019-03-04T16:49:18","date_gmt":"2019-03-04T19:49:18","guid":{"rendered":"http:\/\/www.bunkyorural.com.br\/?p=1253"},"modified":"2019-03-04T16:57:44","modified_gmt":"2019-03-04T19:57:44","slug":"quem-foi-kiyoshi-yamamoto","status":"publish","type":"post","link":"https:\/\/www.bunkyorural.com.br\/index.php\/quem-foi-kiyoshi-yamamoto\/","title":{"rendered":"Quem foi Kiyoshi Yamamoto?"},"content":{"rendered":"<div id=\"attachment_1256\" style=\"width: 241px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.bunkyorural.com.br\/wp-content\/uploads\/2019\/03\/kiyoshi-yamamoto-00.jpg\"><img aria-describedby=\"caption-attachment-1256\" decoding=\"async\" loading=\"lazy\" class=\" wp-image-1256\" src=\"https:\/\/www.bunkyorural.com.br\/wp-content\/uploads\/2019\/03\/kiyoshi-yamamoto-00.jpg\" alt=\"\" width=\"231\" height=\"385\" srcset=\"https:\/\/www.bunkyorural.com.br\/wp-content\/uploads\/2019\/03\/kiyoshi-yamamoto-00.jpg 300w, https:\/\/www.bunkyorural.com.br\/wp-content\/uploads\/2019\/03\/kiyoshi-yamamoto-00-180x300.jpg 180w, https:\/\/www.bunkyorural.com.br\/wp-content\/uploads\/2019\/03\/kiyoshi-yamamoto-00-33x55.jpg 33w\" sizes=\"(max-width: 231px) 100vw, 231px\" \/><\/a><p id=\"caption-attachment-1256\" class=\"wp-caption-text\">Kiyoshi Yamamoto por Tomoo Handa<\/p><\/div>\n<p>Natural de T\u00f3quio, em 1892, Kiyoshi Yamamoto \u00e9 o nome de um pr\u00eamio outorgado anualmente pela Sociedade Brasileira de Cultura Japonesa e de Assist\u00eancia Social aos agricultores, pesquisadores e entidades que se destacaram no desenvolvimento da agricultura brasileira.<\/p>\n<p>Entretanto, numa r\u00e1pida busca pelo Google e encontramos um outro Kiyoshi Yamamoto, um artista pl\u00e1stico internacional radicado na Noruega, e curiosamente nascido no Brasil, em 1983.<\/p>\n<p>O Kiyoshi Yamamoto que estamos falando \u00e9 muito ligado \u00e0 agricultura brasileira. Ele perdeu o pai muito cedo, e tamb\u00e9m o padrasto. Por isso, embora vindo de uma boa fam\u00edlia, passou dificuldades na adolesc\u00eancia. Sem meios para frequentar uma boa escola, estudava em bibliotecas, e foi recompensado quando foi aprovado no curso de Agronomia da Universidade de Tokyo. Naquela \u00e9poca, s\u00f3 os mais ricos podiam estudar. Devido as boas notas que obteve no curso, foi convidado pelo dono da empresa Mitsubishi, Hisaya Iwasaki, a trabalhar na Fazenda Koiwai, que criava cavalos de ra\u00e7a, gado leiteiro e ovelhas. Algum tempo depois, foi-lhe confiada a tarefa de desenvolver a cultura do algod\u00e3o na China. Kiyoshi trabalhou na China por sete anos, e por isso, ele falava fluentemente o mandarim.<\/p>\n<p>Em 1925, Iwasaki confiou-lhe mais um desafio: comandar um projeto agr\u00edcola no Brasil. Kiyoshi deixou a esposa e os filhos no Jap\u00e3o e veio sozinho. Procurou propriedades para adquirir na regi\u00e3o de Campinas e encontrou a Fazenda Ponte Alta, mais tarde rebatizada de Fazenda Monte d&#8217;Este (uma tradu\u00e7\u00e3o literal de Tozan, o bra\u00e7o agr\u00edcola da Mitsubishi). Aprendendo rapidamente o idioma, Yamamoto logo fez amizade com os grandes nomes da sociedade brasileira, e o apoio de entidades como o Instituto Agron\u00f4mico de Campinas. A fazenda original, como em outras existentes no Estado, era coberta de cafezais, afinal, a riqueza paulista girava em torno do caf\u00e9. Kiyoshi tinha uma grande vis\u00e3o e vislumbrava uma realidade bem maior para o Brasil dentro da agricultura.<\/p>\n<p>Para a supresa dos vizinhos, os troncos de \u00e1rvores das \u00e1reas que foram desmatadas foram levados para a serraria e viraram t\u00e1buas e vigas para constru\u00e7\u00e3o. No local desmatado foram plantados eucaliptos para reflorestamento, numa \u00e9poca em que ningu\u00e9m falava sobre isso. Ele tamb\u00e9m introduziu a rota\u00e7\u00e3o de culturas, algo desconhecido no Brasil, mas praticado no Jap\u00e3o. Por exemplo, onde havia planta\u00e7\u00e3o de algod\u00e3o, surge uma planta\u00e7\u00e3o de batata, ou seja, \u00e9 uma forma de aproveitar melhor os nutrientes do solo que cada cultura precisa e tamb\u00e9m para se evitar doen\u00e7as e pragas, que certamente se multiplicam na repeti\u00e7\u00e3o de culturas. Al\u00e9m das madeiras, a Fazenda Tozan tamb\u00e9m fazia os tijolos e telhas que ela precisava utilizando a argila das margens do Rio Atibaia.<\/p>\n<p>Num surto da broca do caf\u00e9, que amea\u00e7ava destruir planta\u00e7\u00f5es inteiras das fazendas, ele resolveu introduzir a vespa de Uganda, que ele descobriu atrav\u00e9s de estudos. A vespa combateu as brocas e n\u00e3o precisou usar nenhum tipo de inceticida, salvando as fazendas do Estado de S\u00e3o Paulo. Essa pesquisa, descrita com detalhes minuciosos, rendeu-lhe o t\u00edtulo de Doutor em Ci\u00eancias Agron\u00f4micas da Universidade de Tokyo.<\/p>\n<p>A import\u00e2ncia da Fazenda Tozan \u00e9 que ela funcionou como uma esta\u00e7\u00e3o experimental, onde os imigrantes japoneses podiam contar com a orienta\u00e7\u00e3o baseada em anos de pesquisas e experimentos. Todos os males que se abatiam na agricultura paulista passavam pela fazenda, onde Yamamoto e seus companheiros tentavam encontrar uma solu\u00e7\u00e3o pr\u00e1tica.<\/p>\n<p>Em 1958, Yamamoto fundou a ABETA &#8211; Associa\u00e7\u00e3o Brasileira de Estudos T\u00e9cnicos da Agricultura, e no mesmo ano, passou a receber t\u00e9cnicos de n\u00edvel m\u00e9dio e superior rec\u00e9m-formados do Jap\u00e3o para serem treinados na Fazenda Tozan. Os estagi\u00e1rios permaneciam por 18 meses e depois seguiam para trabalhar nas cooperativas e empresas prestando assist\u00eancia aos produtores rurais.<\/p>\n<p>Kiyoshi Yamamoto gostava de esportes. Curiosamente, a primeira modalidade introduzida na fazenda foi o futebol. Muito popular entre os colonos que trabalhavam na fazenda, o futebol ganhou um campo com medidas oficiais dentro da propriedade. Mais tarde, a bocha, bilhar, pingue-pongue e at\u00e9 t\u00eanis foram introduzidos. Depois da guerra, uma boa piscina foi constru\u00edda para a pr\u00e1tica da nata\u00e7\u00e3o. Aqui, os famosos &#8220;peixes-voadores&#8221;, entre eles os campe\u00f5es japoneses Furuhashi e Hashizume, se apresentaram na ocasi\u00e3o da visita ao Brasil, em 1949. Os &#8220;peixes-voadores&#8221; ainda hoje s\u00e3o lembrados no Brasil, gra\u00e7as \u00e0 liga\u00e7\u00e3o com o primeiro medalhista ol\u00edmpico brasileiro da nata\u00e7\u00e3o, o saudoso <a href=\"http:\/\/www.imigracaojaponesa.com.br\/index.php\/entrevistas\/tetsuo-okamoto\/\">Tetsuo Okamoto<\/a>.<\/p>\n<p>Em 1955, foi um dos fundadores da Associa\u00e7\u00e3o Paulista de Cultura Japonesa, que daria origem \u00e0 atual Sociedade Brasileira de Cultura Japonesa, da qual foi seu primeiro presidente, ocupando o posto at\u00e9 perto do seu falecimento, ocorrido em julho de 1963, v\u00edtima de c\u00e2ncer pulmonar.<\/p>\n<p>Antes, para as comemora\u00e7\u00f5es do 4\u00ba Centen\u00e1rio da Funda\u00e7\u00e3o da Cidade de S\u00e3o Paulo, o munic\u00edpio montou uma comiss\u00e3o comemorativa, tendo como presidente o poeta Guilherme de Almeida, por sorte, admirador da cultura japonesa, principalmente do haikai (poemas curtos). A comemora\u00e7\u00e3o, que incluia a inaugura\u00e7\u00e3o do pr\u00f3prio Parque do Ibirapuera, contou com v\u00e1rios estandes e pavilh\u00f5es representativos de 19 pa\u00edses. A comunidade nipo-brasileira se empenhou em erguer um pavilh\u00e3o caracter\u00edstico para o Jap\u00e3o no Parque do Ibirapuera, tendo \u00e0 frente da subcomiss\u00e3o do Jap\u00e3o lideran\u00e7as como de Kiyoshi Yamamoto. Gra\u00e7as ao seu prest\u00edgio, foi poss\u00edvel conseguir ajuda do governo japon\u00eas e tamb\u00e9m das lideran\u00e7as da coletividade. Yamamoto trouxe todo o material do Jap\u00e3o para erguer a Casa Japonesa, uma r\u00e9plica do Pal\u00e1cio Katsura de Quioto, com jardim e tanque de carpas. Terminada a comemora\u00e7\u00e3o, como o local era muito visitado pela popula\u00e7\u00e3o, a prefeitura deciciu manter o Pavilh\u00e3o Japon\u00eas, que conta at\u00e9 hoje com uma exposi\u00e7\u00e3o de v\u00e1rios objetos de arte antiga japonesa.<\/p>\n<p>A comiss\u00e3o organizadora do 4\u00ba Centen\u00e1rio, findo o evento, entendeu que deveria-se manter os bons la\u00e7os criados entre os dois povos nos preparativos do 4\u00ba Centen\u00e1rio, o que deu origem \u00e0 Alian\u00e7a Cultural Brasil-Jap\u00e3o, em 1956, sendo os documentos de funda\u00e7\u00e3o assinados no pr\u00f3prio Pavilh\u00e3o. Guilherme de Almeida foi o primeiro presidente da Alian\u00e7a ocupando o posto at\u00e9 1959, quando foi substituido por Kiyoshi Yamamoto.<\/p>\n<a class=\"synved-social-button synved-social-button-share synved-social-size-48 synved-social-resolution-single synved-social-provider-facebook nolightbox\" data-provider=\"facebook\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Facebook\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.bunkyorural.com.br%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F1253&#038;t=Quem%20foi%20Kiyoshi%20Yamamoto%3F&#038;s=100&#038;p&#091;url&#093;=https%3A%2F%2Fwww.bunkyorural.com.br%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F1253&#038;p&#091;images&#093;&#091;0&#093;=https%3A%2F%2Fwww.bunkyorural.com.br%2Fwp-content%2Fuploads%2F2019%2F03%2Fkiyoshi-yamamoto-faceb.jpg&#038;p&#091;title&#093;=Quem%20foi%20Kiyoshi%20Yamamoto%3F\" style=\"font-size: 0px; width:48px;height:48px;margin:0;margin-bottom:5px;margin-right:5px;\"><img alt=\"Facebook\" title=\"Share on Facebook\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"48\" height=\"48\" style=\"display: inline; width:48px;height:48px; margin: 0; padding: 0; border: none; box-shadow: none;\" src=\"https:\/\/www.bunkyorural.com.br\/wp-content\/plugins\/social-media-feather\/synved-social\/image\/social\/regular\/96x96\/facebook.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-48 synved-social-resolution-single synved-social-provider-twitter nolightbox\" data-provider=\"twitter\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fwww.bunkyorural.com.br%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F1253&#038;text=Hey%20check%20this%20out\" style=\"font-size: 0px; width:48px;height:48px;margin:0;margin-bottom:5px;margin-right:5px;\"><img alt=\"twitter\" title=\"Share on Twitter\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"48\" height=\"48\" style=\"display: inline; width:48px;height:48px; margin: 0; padding: 0; border: none; box-shadow: none;\" src=\"https:\/\/www.bunkyorural.com.br\/wp-content\/plugins\/social-media-feather\/synved-social\/image\/social\/regular\/96x96\/twitter.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-48 synved-social-resolution-single synved-social-provider-pinterest nolightbox\" data-provider=\"pinterest\" target=\"_blank\" rel=\"nofollow\" title=\"Pin it with Pinterest\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fwww.bunkyorural.com.br%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F1253&#038;media=https%3A%2F%2Fwww.bunkyorural.com.br%2Fwp-content%2Fuploads%2F2019%2F03%2Fkiyoshi-yamamoto-faceb.jpg&#038;description=Quem%20foi%20Kiyoshi%20Yamamoto%3F\" style=\"font-size: 0px; width:48px;height:48px;margin:0;margin-bottom:5px;margin-right:5px;\"><img alt=\"pinterest\" title=\"Pin it with Pinterest\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"48\" height=\"48\" style=\"display: inline; width:48px;height:48px; margin: 0; padding: 0; border: none; box-shadow: none;\" src=\"https:\/\/www.bunkyorural.com.br\/wp-content\/plugins\/social-media-feather\/synved-social\/image\/social\/regular\/96x96\/pinterest.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-48 synved-social-resolution-single synved-social-provider-linkedin nolightbox\" data-provider=\"linkedin\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Linkedin\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https%3A%2F%2Fwww.bunkyorural.com.br%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F1253&#038;title=Quem%20foi%20Kiyoshi%20Yamamoto%3F\" style=\"font-size: 0px; width:48px;height:48px;margin:0;margin-bottom:5px;margin-right:5px;\"><img alt=\"linkedin\" title=\"Share on Linkedin\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"48\" height=\"48\" style=\"display: inline; width:48px;height:48px; margin: 0; padding: 0; border: none; box-shadow: none;\" src=\"https:\/\/www.bunkyorural.com.br\/wp-content\/plugins\/social-media-feather\/synved-social\/image\/social\/regular\/96x96\/linkedin.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-48 synved-social-resolution-single synved-social-provider-mail nolightbox\" data-provider=\"mail\" rel=\"nofollow\" title=\"Share by email\" href=\"mailto:?subject=Quem%20foi%20Kiyoshi%20Yamamoto%3F&#038;body=Hey%20check%20this%20out:%20https%3A%2F%2Fwww.bunkyorural.com.br%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F1253\" style=\"font-size: 0px; width:48px;height:48px;margin:0;margin-bottom:5px;\"><img alt=\"mail\" title=\"Share by email\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"48\" height=\"48\" style=\"display: inline; width:48px;height:48px; margin: 0; padding: 0; border: none; box-shadow: none;\" src=\"https:\/\/www.bunkyorural.com.br\/wp-content\/plugins\/social-media-feather\/synved-social\/image\/social\/regular\/96x96\/mail.png\" \/><\/a>","protected":false},"excerpt":{"rendered":"<p>Natural de T\u00f3quio, em 1892, Kiyoshi Yamamoto \u00e9 o nome de um pr\u00eamio outorgado anualmente pela Sociedade Brasileira de Cultura Japonesa e de Assist\u00eancia Social aos agricultores, pesquisadores e entidades [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1259,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[1],"tags":[34,35],"jetpack_featured_media_url":"https:\/\/www.bunkyorural.com.br\/wp-content\/uploads\/2019\/03\/kiyoshi-yamamoto-faceb.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3P1bn-kd","_links":{"self":[{"href":"https:\/\/www.bunkyorural.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1253"}],"collection":[{"href":"https:\/\/www.bunkyorural.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bunkyorural.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bunkyorural.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bunkyorural.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1253"}],"version-history":[{"count":3,"href":"https:\/\/www.bunkyorural.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1253\/revisions"}],"predecessor-version":[{"id":1257,"href":"https:\/\/www.bunkyorural.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1253\/revisions\/1257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bunkyorural.com.br\/index.php\/wp-json\/wp\/v2\/media\/1259"}],"wp:attachment":[{"href":"https:\/\/www.bunkyorural.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bunkyorural.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bunkyorural.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}